{"id":63,"count":1,"description":"","link":"https:\/\/tehronmachines.ro\/pro\/category\/actualitati\/","name":"ACTUALIT\u0102\u021aI","slug":"actualitati","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/tehronmachines.ro\/pro\/wp-json\/wp\/v2\/categories\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tehronmachines.ro\/pro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tehronmachines.ro\/pro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/tehronmachines.ro\/pro\/wp-json\/wp\/v2\/posts?categories=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}